{"id":26,"count":3,"description":"Conciertos Municipales: Vive la cultura de nuestra ciudad a trav\u00e9s de una programaci\u00f3n musical de calidad. Disfruta de conciertos gratuitos y de pago en los mejores escenarios. \u00a1Te esperamos!","link":"https:\/\/eventosmogan.com\/en\/product-category\/conciertos\/","name":"Conciertos","slug":"conciertos","taxonomy":"product_cat","parent":0,"meta":{"group_of_quantity":""},"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/eventosmogan.com\/en\/wp-json\/wp\/v2\/product_cat\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventosmogan.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/eventosmogan.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/eventosmogan.com\/en\/wp-json\/wp\/v2\/product?product_cat=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}